{"id":7344,"date":"2024-06-21T16:59:57","date_gmt":"2024-06-21T19:59:57","guid":{"rendered":"https:\/\/sengemg.clkaqui.com.br\/?p=7344"},"modified":"2024-06-21T16:59:57","modified_gmt":"2024-06-21T19:59:57","slug":"amplie-suas-competencias-e-alcance-novos-patamares-na-carreira","status":"publish","type":"post","link":"https:\/\/sengemg.clkaqui.com.br\/index.php\/2024\/06\/21\/amplie-suas-competencias-e-alcance-novos-patamares-na-carreira\/","title":{"rendered":"Amplie suas compet\u00eancias e alcance novos patamares na carreira!"},"content":{"rendered":"\n\n\n<p>Nossas aulas gratuitas j\u00e1 est\u00e3o dispon\u00edveis.<\/p>\n\n\n\n<p>Gra\u00e7as \u00e0 parceria com o CREA, voc\u00ea pode acessar cursos gratuitos, de onde estiver. Sem custos!<\/p>\n\n\n\n<p>Estamos sempre buscando evoluir nossos profissionais. Aproveite essa chance \u00fanica!<\/p>\n\n\n\n<p>Acesse <a href=\"https:\/\/qualificar.crea-mg.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/qualificar.crea-mg.com.br\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nossas aulas gratuitas j\u00e1 est\u00e3o dispon\u00edveis. Gra\u00e7as \u00e0 parceria com o CREA, voc\u00ea pode acessar cursos gratuitos, de onde estiver. Sem custos! Estamos sempre buscando evoluir nossos profissionais. Aproveite essa chance \u00fanica! Acesse https:\/\/qualificar.crea-mg.com.br\/<\/p>\n","protected":false},"author":9,"featured_media":7345,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-7344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos"],"acf":[],"_links":{"self":[{"href":"https:\/\/sengemg.clkaqui.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sengemg.clkaqui.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sengemg.clkaqui.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sengemg.clkaqui.com.br\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sengemg.clkaqui.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7344"}],"version-history":[{"count":1,"href":"https:\/\/sengemg.clkaqui.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7344\/revisions"}],"predecessor-version":[{"id":7346,"href":"https:\/\/sengemg.clkaqui.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7344\/revisions\/7346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sengemg.clkaqui.com.br\/index.php\/wp-json\/wp\/v2\/media\/7345"}],"wp:attachment":[{"href":"https:\/\/sengemg.clkaqui.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sengemg.clkaqui.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sengemg.clkaqui.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}